{"id":12014,"date":"2022-02-17T15:45:41","date_gmt":"2022-02-17T14:45:41","guid":{"rendered":"http:\/\/bc2.elwood.agency\/?p=12014"},"modified":"2024-07-22T10:44:32","modified_gmt":"2024-07-22T08:44:32","slug":"trend-darredamento-2022-minimal-e-naturale","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/","title":{"rendered":"Trend d&#8217;arredamento 2022: Minimal e Naturale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12014\" class=\"elementor elementor-12014\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b699736 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b699736\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58f8deb2\" data-id=\"58f8deb2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c577998 elementor-widget elementor-widget-text-editor\" data-id=\"5c577998\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph -->\n<p>Il nuovo anno \u00e8 appena cominciato e i\u00a0<a href=\"https:\/\/www.westwing.it\/inspiration\/tendenze\/trend-report\/tendenze-interior-design-2022\/#:~:text=Sul%20filo%20del%20tema%20%E2%80%9Csostenibilit%C3%A0,tossiche%20e%20mobili%20di%20recupero.\"><strong>trend d&#8217;arredamento 2022\u00a0<\/strong><\/a>cominciano a farsi strada, sia per quanto riguarda le abitazioni private che le strutture ricettive come B&amp;B e Agriturismi.<br \/>Quest&#8217;anno si assister\u00e0 a un&#8217;evoluzione della \u201c<em>corrente di pensiero<\/em>\u201d gi\u00e0 diffusa e condivisa nel corso del 2021: a farsi largo saranno principalmente uno stile minimale caratterizzato da materiali e colori naturali.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Che significa?<br \/>Significa che abitazioni, hotel, agriturismi, bed&amp;breakfast potranno risplendere di una luce nuova, grazie ad ambienti ampi (e\u00a0<em>open<\/em>), comodi e multifunzionali: largo a soluzioni che possano soddisfare le esigenze di tutti, senza sacrificare troppo spazio e rendendo il tutto molto pi\u00f9\u00a0<em>smart<\/em>.<br \/>Arredi semplici, dalle linee pulite, senza troppi dettagli e particolari superflui, confortevoli, facili da spostare e ideali per suddividere e organizzare le camere in modo intuitivo e utile.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Fra i materiali da prediligere sicuramente il legno, la pietra, il marmo e il vetro, che \u2013 per motivi diversi \u2013 sapranno dare luminosit\u00e0, calore e personalit\u00e0, aggiungendo un tocco unico a ogni ambiente.<br \/>I colori del 2022?<br \/>Sicuramente i colori della terra (marroni, beige, sabbia&#8230;), il blu e il verde, due tonalit\u00e0 note per le propriet\u00e0 rilassanti. Non mancher\u00e0 \u2013 per\u00f2 \u2013 anche il\u00a0<strong>Very Peri<\/strong>\u00a0scelto da Pantone, di cui abbiamo parlato\u00a0in un articolo precedente.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Tutti questi elementi lasciano, naturalmente, intravedere quali saranno gli stili pi\u00f9 importanti per i\u00a0<strong>trend d&#8217;arredamento 2022<\/strong>: minimal, rustico e nordico saranno al centro del mondo dell&#8217;arredo, guidando le scelte che di chi desiderer\u00e0 aggiornare gli interni di case e strutture.<br \/>Siete curiosi?<br \/>Nel nostro shop \u00e8 presente la\u00a0<a href=\"https:\/\/boschiscontract.it\/residential\/linea\/linea-modern\/\">Linea Modern<\/a>, che interpreta al meglio le esigenze di quest&#8217;anno!<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>I nostri esperti sapranno guidarvi nella scelta delle soluzioni perfette per ogni tipo di agriturismo o b&amp;b:\u00a0<a href=\"https:\/\/boschiscontract.it\/residential\/contatti\/\">scriveteci o contattateci telefonicamente<\/a>, vi forniremo una assistenza su misura!<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I trend d&#8217;arredamento del 2022 includono uno stile minimal e dei materiali naturali: ecco i suggerimenti per quest&#8217;anno!<\/p>\n","protected":false},"author":1,"featured_media":12016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[17],"class_list":["post-12014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli","tag-arredamento-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trend d&#039;arredamento 2022: Minimal e Naturale - Boschis Contract Residential<\/title>\n<meta name=\"description\" content=\"I trend d&#039;arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&amp;b e agriturismi!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trend d&#039;arredamento 2022: Minimal e Naturale - Boschis Contract Residential\" \/>\n<meta property=\"og:description\" content=\"I trend d&#039;arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&amp;b e agriturismi!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T14:45:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T08:44:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"Trend d&#8217;arredamento 2022: Minimal e Naturale\",\"datePublished\":\"2022-02-17T14:45:41+00:00\",\"dateModified\":\"2024-07-22T08:44:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg\",\"keywords\":[\"arredamento b&amp;b\"],\"articleSection\":[\"Consigli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\",\"name\":\"Trend d'arredamento 2022: Minimal e Naturale - Boschis Contract Residential\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg\",\"datePublished\":\"2022-02-17T14:45:41+00:00\",\"dateModified\":\"2024-07-22T08:44:32+00:00\",\"description\":\"I trend d'arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&b e agriturismi!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg\",\"width\":870,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trend d&#8217;arredamento 2022: Minimal e Naturale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trend d'arredamento 2022: Minimal e Naturale - Boschis Contract Residential","description":"I trend d'arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&b e agriturismi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/","og_locale":"it_IT","og_type":"article","og_title":"Trend d'arredamento 2022: Minimal e Naturale - Boschis Contract Residential","og_description":"I trend d'arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&b e agriturismi!","og_url":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2022-02-17T14:45:41+00:00","article_modified_time":"2024-07-22T08:44:32+00:00","og_image":[{"width":870,"height":489,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg","type":"image\/jpeg"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"Trend d&#8217;arredamento 2022: Minimal e Naturale","datePublished":"2022-02-17T14:45:41+00:00","dateModified":"2024-07-22T08:44:32+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg","keywords":["arredamento b&amp;b"],"articleSection":["Consigli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/","url":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/","name":"Trend d'arredamento 2022: Minimal e Naturale - Boschis Contract Residential","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg","datePublished":"2022-02-17T14:45:41+00:00","dateModified":"2024-07-22T08:44:32+00:00","description":"I trend d'arredamento 2022 comprendono materiali e colori naturali, spazi aperti e stile minimale: scopri come arredare b&b e agriturismi!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/02\/110-single-default.jpg","width":870,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/trend-darredamento-2022-minimal-e-naturale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"Trend d&#8217;arredamento 2022: Minimal e Naturale"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/12014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=12014"}],"version-history":[{"count":11,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/12014\/revisions"}],"predecessor-version":[{"id":15926,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/12014\/revisions\/15926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/12016"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=12014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=12014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=12014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}