{"id":13569,"date":"2022-10-13T12:08:00","date_gmt":"2022-10-13T10:08:00","guid":{"rendered":"https:\/\/bc2.elwood.agency\/?p=13569"},"modified":"2024-10-29T09:06:28","modified_gmt":"2024-10-29T08:06:28","slug":"halloween-come-arredare-un-bb-a-tema","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/","title":{"rendered":"Halloween: come arredare un B&amp;B a tema"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13569\" class=\"elementor elementor-13569\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21f17bad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21f17bad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c58e698\" data-id=\"7c58e698\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62577b20 elementor-widget elementor-widget-text-editor\" data-id=\"62577b20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph -->\n<p>L&#8217;arredamento \u00e8 lo\u00a0<em>spirito<\/em>\u00a0di una struttura ricettiva, possiamo quasi dire la sua anima.<br \/>Realizzare spazi esterni ed interni coerenti, confortevoli e di alta qualit\u00e0 ci permette di creare armonia ed equilibrio, dando ai visitatori la possibilit\u00e0 di sentirsi come a casa.<br \/>Alcune ricorrenze facilitano il compito, permettendo ai proprietari di agriturismi e B&amp;B di sbizzarrirsi con allestimenti a tema che attirano, divertono e affascinano.<br \/><br \/>Fra pochissimi giorni sar\u00e0 la volta di\u00a0<strong>Halloween<\/strong>, una festa d&#8217;oltreoceano che ha preso sempre pi\u00f9 piede anche da noi e che &#8211; pur non rappresentando una vera e propria tradizione classica &#8211; sta <a href=\"https:\/\/www.focusjunior.it\/comportamento\/feste\/halloween\/halloween-quando-si-festeggia-e-perche\/\">coinvolgendo sempre di pi\u00f9 grandi e piccini<\/a>, ispirando party in costume, maratone horror e travestimenti da togliere il sonno.<br \/><br \/>Anche una struttura ricettiva pu\u00f2 cambiare la sua veste e prepararsi a questo evento: ma<strong>\u00a0come arredare un B&amp;B a tema?<br \/><br \/><\/strong>Nel caso di Halloween possiamo seguire due strade:<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>L&#8217;allestimento elegante e privo di elementi eccessivamente spaventosi.<br \/>In questo caso non si celebra tanto il 31 ottobre quanto l&#8217;arrivo del periodo freddo e il cambiamento delle stagioni: largo, quindi, alla palette dell&#8217;arancio e a quella del verde foresta, con nuance calde e accoglienti, in perfetto accordo fra loro. Ad accompagnare il cambiamento cromatico anche l&#8217;aggiunta di zucche decorative, rametti anche dipinti, bacche, foglie, pigne&#8230; insomma tutto ci\u00f2 che pu\u00f2 farci pensare a una romantica passeggiata in mezzo al bosco che si tinge di rosso! Dal punto di vista degli accessori, fine ottobre \u00e8 anche il momento perfetto per aggiungere lanterne e candele, vasi trasparenti e oggetti decorativi in grado di far rimbalzare la luce, creando un effetto soffuso davvero magico.<br \/>A dominare deve essere la raffinatezza, alla base di combo funzionali e belle da vedere!<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>L&#8217;allestimento in pieno stile Halloween.<br \/>Cio\u00e8, ragnatele finte, specchi inquietanti, zucche intagliate, cartelli fatti a mano, fantasmi realizzati con le lenzuola bianche, scheletri posizionati in punti strategici e tantissimi dolcetti sempre disponibili. Un piccolo consiglio: limitiamo questa ondata &#8220;<em>spooky<\/em>&#8221; ai soli spazi esterni e agli ambienti comuni.<br \/>Nelle camere, inseriamo pochi elementi coerenti &#8211; come delle candele o delle piccole zucche &#8211; posizionate su una scrivania, un tavolino o sulla finestra.<br \/>L&#8217;idea \u00e8 sempre quella di non invadere eccessivamente gli spazi privati, lasciando gli allestimenti pi\u00f9 audaci alle zone frequentate da tutti.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>Nell&#8217;<a href=\"https:\/\/boschiscontract.it\/residential\/come-arredare-il-bb\/\">arredare un B&amp;B<\/a> per Halloween non c&#8217;\u00e8 giusto o sbagliato: basta seguire il proprio gusto, mettendo sempre in primo piano l&#8217;esperienza dei clienti!<br \/><br \/>Sei curioso e vuoi saperne di pi\u00f9?<br \/>Ti interessa una valutazione professionale per l&#8217;arredamento della tua struttura?<br \/><a href=\"https:\/\/boschiscontract.it\/residential\/contatti\/\">Contattaci e ti daremo maggiori informazioni!<\/a><\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Arredare un B&#038;B per Halloween significa scegliere fra stili e possibilit\u00e0 diverse: vediamo insieme come fare!<\/p>\n","protected":false},"author":1,"featured_media":13570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[17],"class_list":["post-13569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli","tag-arredamento-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential<\/title>\n<meta name=\"description\" content=\"Arredare un B&amp;B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential\" \/>\n<meta property=\"og:description\" content=\"Arredare un B&amp;B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-13T10:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T08:06:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1222\" \/>\n\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"Halloween: come arredare un B&amp;B a tema\",\"datePublished\":\"2022-10-13T10:08:00+00:00\",\"dateModified\":\"2024-10-29T08:06:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\"},\"wordCount\":443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png\",\"keywords\":[\"arredamento b&amp;b\"],\"articleSection\":[\"Consigli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\",\"name\":\"Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png\",\"datePublished\":\"2022-10-13T10:08:00+00:00\",\"dateModified\":\"2024-10-29T08:06:28+00:00\",\"description\":\"Arredare un B&B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png\",\"width\":1222,\"height\":782,\"caption\":\"Arredamento B&B per Halloween\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halloween: come arredare un B&amp;B a tema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential","description":"Arredare un B&B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/","og_locale":"it_IT","og_type":"article","og_title":"Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential","og_description":"Arredare un B&B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!","og_url":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2022-10-13T10:08:00+00:00","article_modified_time":"2024-10-29T08:06:28+00:00","og_image":[{"width":1222,"height":782,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png","type":"image\/png"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"Halloween: come arredare un B&amp;B a tema","datePublished":"2022-10-13T10:08:00+00:00","dateModified":"2024-10-29T08:06:28+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/"},"wordCount":443,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png","keywords":["arredamento b&amp;b"],"articleSection":["Consigli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/","url":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/","name":"Halloween: come arredare un B&amp;B a tema - Boschis Contract Residential","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png","datePublished":"2022-10-13T10:08:00+00:00","dateModified":"2024-10-29T08:06:28+00:00","description":"Arredare un B&B per Halloween significa scegliere fra spaventoso e raffinato, spooky e autunnale: vediamo come fare al meglio!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/arredamento_bb_halloween.png","width":1222,"height":782,"caption":"Arredamento B&B per Halloween"},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/halloween-come-arredare-un-bb-a-tema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"Halloween: come arredare un B&amp;B a tema"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=13569"}],"version-history":[{"count":10,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13569\/revisions"}],"predecessor-version":[{"id":15791,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13569\/revisions\/15791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/13570"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=13569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=13569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=13569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}