{"id":13572,"date":"2022-10-24T12:10:00","date_gmt":"2022-10-24T10:10:00","guid":{"rendered":"https:\/\/bc2.elwood.agency\/?p=13572"},"modified":"2024-07-22T10:04:38","modified_gmt":"2024-07-22T08:04:38","slug":"i-colori-dellautunno-2022","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/","title":{"rendered":"I colori dell\u2019autunno 2022"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13572\" class=\"elementor elementor-13572\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cd8123 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cd8123\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72ef8024\" data-id=\"72ef8024\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27ad0341 elementor-widget elementor-widget-text-editor\" data-id=\"27ad0341\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph -->\n<p>I cambi di stagione \u2013 con le trasformazioni della luce, della natura che ci circonda e delle temperature \u2013 suggeriscono non solo un cambio di armadio, ma anche un cambio\u2026\u00a0<strong>d\u2019arredo<\/strong>!<br \/>Le modifiche di tonalit\u00e0, tessuti e stili non riguardano solo le abitazioni private, ma anche gli alberghi, i b&amp;b, gli agriturismi e tutte le altre tipologie di struttura ricettiva: l\u2019autunno, in particolare, ispira grandi rivoluzioni, merito del suo dinamismo e dei suoi tratti insieme caldi e accoglienti.<br \/>Non si tratta solo della fine dell\u2019estate, ma della nascita di un mondo completamente nuovo, divertente e vivace.<br \/><br \/>La stagione autunnale \u00e8 \u2013 forse \u2013 la pi\u00f9 caratteristica per quanto riguarda i colori: ogni anno, l\u2019attesa che precede il \u201clancio\u201d delle tonalit\u00e0 di ottobre, novembre e dicembre \u00e8 sempre lunga e spasmodica e coinvolge davvero tutti, dall\u2019alta moda ai tessuti per la casa.<br \/><strong>Ma quali sono i colori dell\u2019autunno 2022?<br \/><br \/><\/strong>Le novit\u00e0 sono poche, circondate da numerosi capisaldi del periodo:<\/p>\n<!-- \/wp:paragraph --><!-- wp:list {\"ordered\":true} -->\n<ol><!-- wp:list-item -->\n<li>a dominare \u00e8 sicuramente il legno, con tutte le sue tonalit\u00e0 del beige e del marrone. Questo materiale ci fa subito pensare a serate in casa davanti al caminetto, un buon libro sul divano, una copertina sulle gambe e una cioccolata nella tazza: aggiungere particolari in legno o utilizzarne le tonalit\u00e0 pi\u00f9 riconoscibili \u00e8 il modo migliore per lasciarsi alle spalle l\u2019estate e aspettare con gioia l\u2019inverno;<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>seguono i colori della natura, nella loro versione pi\u00f9 tenue: il verde salvia e cachi, l\u2019arancio \u201czucca\u201d non troppo acceso, il crema, il color sabbia e il lilla per un tocco divertente. Queste tonalit\u00e0 sono sobrie ed eleganti, piene di profondit\u00e0 e vitalit\u00e0, capaci di trasmettere calore e serenit\u00e0;<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li>infine, non pu\u00f2 mancare l\u2019alternanza con colori pi\u00f9 intensi, come il verde oliva, il giallo ocra, il grigio, il magenta (protagonista di tutte le vetrine fin dalla scorsa estate) e il blu. L\u2019abbinamento di tonalit\u00e0 pi\u00f9 e meno sature \u2013 magari con motivi geometrici e il mix di stile tradizionale e contemporaneo \u2013 permette di realizzare ambienti a prova di autunno!<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>Dal punto di vista degli elementi di arredo, non possono \u2013 poi \u2013 mancare pouf, plaid, coperte morbide in lana, asciugamani pesanti e fantasie audaci come il\u00a0<a href=\"https:\/\/be-a.abilmente.org\/news\/tutto-sul-patchwork\/\"><em>patchwork<\/em><\/a>.<br \/><br \/>Sei curioso di sapere come <a href=\"https:\/\/boschiscontract.it\/residential\/arredamento-country\/\">modificare l\u2019arredo<\/a> della tua struttura ricettiva, magari utilizzando i colori dell&#8217;autunno 2022?<br \/><a href=\"https:\/\/boschiscontract.it\/residential\/contatti\/\">Contattaci<\/a>\u00a0per un consiglio e per una assistenza su misura!<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>I colori dell&#8217;autunno 2022 mixano grandi classici e qualche novit\u00e0: vediamoli insieme!<\/p>\n","protected":false},"author":1,"featured_media":13573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[17],"class_list":["post-13572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli","tag-arredamento-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Colori autunno 2022 - Boschis Contract<\/title>\n<meta name=\"description\" content=\"I colori dell&#039;autunno 2022 non sono solo marrone e beige: leggi l&#039;articolo per scoprire come arredare al meglio la tua struttura!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colori autunno 2022 - Boschis Contract\" \/>\n<meta property=\"og:description\" content=\"I colori dell&#039;autunno 2022 non sono solo marrone e beige: leggi l&#039;articolo per scoprire come arredare al meglio la tua struttura!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-24T10:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T08:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1114\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"I colori dell\u2019autunno 2022\",\"datePublished\":\"2022-10-24T10:10:00+00:00\",\"dateModified\":\"2024-07-22T08:04:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\"},\"wordCount\":395,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png\",\"keywords\":[\"arredamento b&amp;b\"],\"articleSection\":[\"Consigli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\",\"name\":\"Colori autunno 2022 - Boschis Contract\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png\",\"datePublished\":\"2022-10-24T10:10:00+00:00\",\"dateModified\":\"2024-07-22T08:04:38+00:00\",\"description\":\"I colori dell'autunno 2022 non sono solo marrone e beige: leggi l'articolo per scoprire come arredare al meglio la tua struttura!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png\",\"width\":1114,\"height\":856,\"caption\":\"colori autunno 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I colori dell\u2019autunno 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colori autunno 2022 - Boschis Contract","description":"I colori dell'autunno 2022 non sono solo marrone e beige: leggi l'articolo per scoprire come arredare al meglio la tua struttura!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/","og_locale":"it_IT","og_type":"article","og_title":"Colori autunno 2022 - Boschis Contract","og_description":"I colori dell'autunno 2022 non sono solo marrone e beige: leggi l'articolo per scoprire come arredare al meglio la tua struttura!","og_url":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2022-10-24T10:10:00+00:00","article_modified_time":"2024-07-22T08:04:38+00:00","og_image":[{"width":1114,"height":856,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png","type":"image\/png"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"I colori dell\u2019autunno 2022","datePublished":"2022-10-24T10:10:00+00:00","dateModified":"2024-07-22T08:04:38+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/"},"wordCount":395,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png","keywords":["arredamento b&amp;b"],"articleSection":["Consigli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/","url":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/","name":"Colori autunno 2022 - Boschis Contract","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png","datePublished":"2022-10-24T10:10:00+00:00","dateModified":"2024-07-22T08:04:38+00:00","description":"I colori dell'autunno 2022 non sono solo marrone e beige: leggi l'articolo per scoprire come arredare al meglio la tua struttura!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/11\/colori_autunno_2022.png","width":1114,"height":856,"caption":"colori autunno 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/i-colori-dellautunno-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"I colori dell\u2019autunno 2022"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=13572"}],"version-history":[{"count":11,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13572\/revisions"}],"predecessor-version":[{"id":15782,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/13572\/revisions\/15782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/13573"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=13572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=13572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=13572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}