{"id":14839,"date":"2023-10-25T10:07:02","date_gmt":"2023-10-25T08:07:02","guid":{"rendered":"http:\/\/www.residential.residential.boschiscontract.it\/?p=14839"},"modified":"2024-10-31T09:36:38","modified_gmt":"2024-10-31T08:36:38","slug":"bb-a-tema-halloween-unesperienza-spaventosamente-divertente","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/","title":{"rendered":"B&#038;B a tema Halloween: un&#8217;esperienza spaventosamente divertente"},"content":{"rendered":"\n<p>La Notte delle Streghe \u00e8 una delle pi\u00f9 attese da tutti gli amanti del terrore, del mistero e dell\u2019incubo: quella del 31 ottobre \u00e8 una delle festivit\u00e0 che, forse, si sentono un po\u2019 meno nel nostro paese, ma gli appassionati non mancano!<\/p>\n\n\n\n<p>Certo, il fatto che ci siano anche dei <em>dolcetti<\/em> rende il tutto molto pi\u00f9 piacevole\u2026<br><br><strong>Arredare un B&amp;B a tema Halloween<\/strong> significa non solo attirare l\u2019attenzione di chi \u00e8 fan di queste celebrazioni un po\u2019 \u201c<em>spooky<\/em>\u201d, ma anche cogliere l\u2019occasione per trasformare la propria struttura ricettiva nel set ideale di feste super divertenti e momenti indimenticabili per grandi e piccini.<br>Vediamo qualche consiglio!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arredamento spaventoso per gli interni<\/h2>\n\n\n\n<p>Nel mese di ottobre \u2013 e in particolare nelle ultime due settimane prima dell\u2019arrivo di novembre \u2013 l\u2019<a href=\"https:\/\/boschiscontract.it\/residential\/tendenze-autunnali-per-larredo-di-bb-e-agriturismi\/\">arredo del B&amp;B<\/a> pu\u00f2 essere completamente stravolto e impreziosito dall\u2019aggiunta di alcuni accessori a tema che non possono proprio mancare quando si parla di horror:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zucche intagliate (o Jack-o\u2019-Lantern), zucche pi\u00f9 piccole di svariati colori e foglie rosse autunnali;<\/li>\n\n\n\n<li>Vecchi giornali e libri vintage, caratterizzati da pagine ingiallite e titoli spaventosi (creare queste decorazioni potrebbe essere anche un progetto DIY super coinvolgente per il mese di settembre);<\/li>\n\n\n\n<li>Finte tele di ragno\u2026 e finte vedove nere appese qui e l\u00ec;<\/li>\n\n\n\n<li>Maschere spaventose, teschi e scheletri;<\/li>\n\n\n\n<li>Luci soffuse, lampadine rosse e verdi, led che si accendono inaspettatamente al passaggio degli ospiti.<\/li>\n<\/ul>\n\n\n\n<p>Non possono mancare, poi, gli effetti sonori, come porte scricchiolanti, risate demoniache, sussurri dagli angoli bui.<br>Come fare?<br>Alcuni servizi \u2013 come <a href=\"https:\/\/open.spotify.com\/intl-it\" target=\"_blank\" rel=\"noreferrer noopener\">Spotify<\/a> o <a href=\"https:\/\/www.youtube.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Youtube<\/a> \u2013 hanno archivi infiniti di musiche, canzoni e classici di Halloween, sempre utili per creare la giusta atmosfera da brivido!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Anche gli esterni vogliono la loro parte<\/h2>\n\n\n\n<p>Per <strong>arredare un B&amp;B a tema Halloween<\/strong> non possono mancare alcune piccole accortezze per gli spazi esterni, perfetti per ospitare anche decorazioni di grandi dimensioni.<br>Qualche idea?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Creature giganti, come ragni gonfiabili, topolini non troppo spaventosi, mummie e streghe;<\/li>\n\n\n\n<li>Una macchina per la nebbia, per creare quel vapore spesso e bianco che rende ogni spazio ancora pi\u00f9 terrificante;<\/li>\n\n\n\n<li>Una coltre di ragnatele tese fra alberi e cespugli;<\/li>\n\n\n\n<li>Zucche intagliate e decorate con tantissime candele accese;<\/li>\n\n\n\n<li>Lanterne soffuse per creare angoli inquietanti.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019idea potrebbe essere quella di trasformare il B&amp;B in una vera e propria casa abbandonata\u2026 ma solo in apparenza!<br>All\u2019interno si nascondono \u2013 come sempre \u2013 accoglienza, comodit\u00e0 e tantissimo divertimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il 31 \u00e8 una festa!<\/h2>\n\n\n\n<p>La notte del 31 ottobre \u00e8 perfetta per organizzare una festa in costume, proponendo \u2013 magari \u2013 cibo e bevande a tema. Fulcro della serata: un contest per selezionare l\u2019invitato con il travestimento migliore!<br><br><strong>Arredare un B&amp;B a tema Halloween<\/strong> permette di coinvolgere i propri clienti in una celebrazione diversa dal solito, una vera e propria esperienza immersiva!<br>Quali decorazioni non possono mancare secondo te?<\/p>\n\n\n<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/<br \/>\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"494\" src=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/halloween-1024x632.jpeg\" alt=\"b&amp;b halloween\" loading=\"lazy\" srcset=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/halloween-1024x632.jpeg 1024w, https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/halloween-300x185.jpeg 300w, https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/halloween-768x474.jpeg 768w, https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/halloween.jpeg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La Notte delle Streghe \u00e8 una delle pi\u00f9 attese da tutti gli amanti del terrore, del mistero e dell\u2019incubo: quella del 31 ottobre \u00e8 una delle festivit\u00e0 che, forse, si sentono un po\u2019 meno nel nostro paese, ma gli appassionati non mancano! Certo, il fatto che ci siano anche dei dolcetti rende il tutto molto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[38],"class_list":["post-14839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli","tag-arredare-un-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arredare un B&amp;B a tema Halloween - Boschis Contract<\/title>\n<meta name=\"description\" content=\"Per arredare un B&amp;B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arredare un B&amp;B a tema Halloween - Boschis Contract\" \/>\n<meta property=\"og:description\" content=\"Per arredare un B&amp;B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-25T08:07:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-31T08:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"B&#038;B a tema Halloween: un&#8217;esperienza spaventosamente divertente\",\"datePublished\":\"2023-10-25T08:07:02+00:00\",\"dateModified\":\"2024-10-31T08:36:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\"},\"wordCount\":473,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg\",\"keywords\":[\"arredare un B&amp;B\"],\"articleSection\":[\"Consigli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\",\"name\":\"Arredare un B&B a tema Halloween - Boschis Contract\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg\",\"datePublished\":\"2023-10-25T08:07:02+00:00\",\"dateModified\":\"2024-10-31T08:36:38+00:00\",\"description\":\"Per arredare un B&B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg\",\"width\":1280,\"height\":855,\"caption\":\"arredare un B&B a tema Halloween\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B&#038;B a tema Halloween: un&#8217;esperienza spaventosamente divertente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arredare un B&B a tema Halloween - Boschis Contract","description":"Per arredare un B&B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/","og_locale":"it_IT","og_type":"article","og_title":"Arredare un B&B a tema Halloween - Boschis Contract","og_description":"Per arredare un B&B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!","og_url":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2023-10-25T08:07:02+00:00","article_modified_time":"2024-10-31T08:36:38+00:00","og_image":[{"width":1280,"height":855,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg","type":"image\/jpeg"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"B&#038;B a tema Halloween: un&#8217;esperienza spaventosamente divertente","datePublished":"2023-10-25T08:07:02+00:00","dateModified":"2024-10-31T08:36:38+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/"},"wordCount":473,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg","keywords":["arredare un B&amp;B"],"articleSection":["Consigli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/","url":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/","name":"Arredare un B&B a tema Halloween - Boschis Contract","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg","datePublished":"2023-10-25T08:07:02+00:00","dateModified":"2024-10-31T08:36:38+00:00","description":"Per arredare un B&B a tema Halloween bastano luci soffuse, finte ragnatele e tanta, tanta, fantasia: scopri i nostri consigli!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2023\/10\/tree-736877_1280.jpeg","width":1280,"height":855,"caption":"arredare un B&B a tema Halloween"},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/bb-a-tema-halloween-unesperienza-spaventosamente-divertente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"B&#038;B a tema Halloween: un&#8217;esperienza spaventosamente divertente"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/14839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=14839"}],"version-history":[{"count":11,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/14839\/revisions"}],"predecessor-version":[{"id":16389,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/14839\/revisions\/16389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/14840"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=14839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=14839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=14839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}