{"id":3817,"date":"2021-12-02T15:37:14","date_gmt":"2021-12-02T14:37:14","guid":{"rendered":"http:\/\/bc2.elwood.agency\/?p=3817"},"modified":"2024-06-15T14:53:52","modified_gmt":"2024-06-15T12:53:52","slug":"boschis-interior-design-per-piccoli-sogni","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/","title":{"rendered":"Boschis, Interior Design per piccoli sogni"},"content":{"rendered":"<p><strong>Boschis Contract<\/strong>\u00a0\u00e8 figlia della storica azienda di Edoardo Boschis che fin dal 1912 si occupa di arredi su misura. Di generazione in generazione, la Boschis ha realizzato collaborazioni con famosissimi studi di\u00a0<strong>interior design<\/strong>\u00a0che da sempre arredano con stile e creativit\u00e0 uffici, residence, alberghi, auditorium e negozi.<\/p>\n<p>La sede principale di Mappano si occupa della costruzioniedi mobili che sono vere e proprie opere, poich\u00e9 riproducono fedelmente il lavoro del progettista trasformando la sua immaginazione in realt\u00e0.<br \/>Lo staff esecutivo si occupa di creare mobili e forniture utilizzando diversi materiali come legno, marmo, vetro tessuti e plastiche, mentre lo staff tecnico assiste il cliente nella progettazione dell\u2019ambiente.<\/p>\n<p>La pluriennale esperienza di Boschis nell\u2019arredamento di prestigiosi hotel, ha fatto si che ponesse il suo focus anche nelle piccole strutture ricettive. Nell\u2019ultimo decennio infatti, sono nati moltissimi bed and breakfast, agriturismi e affittacamere che sono molto apprezzati dai viaggiatori che desiderano vivere in maniera pi\u00f9 \u201cnaturale\u201d la loro vacanza.<\/p>\n<p>Boschis Contract si occupa di aiutare questi nuovi professionisti nella realizzazione di camere private e ambienti comuni puntando sull\u2019originalit\u00e0. Il catalogo offre diverse proposte che spaziano tra diversi stili, dal country al moderno, per far si che la piccola struttura possa distinguersi con una personalit\u00e0 ben precisa.<br \/>Boschis infatti non solo offre mobili gi\u00e0 pronti che garantiscono resistenza e praticit\u00e0, ma aiuta il cliente nella scelta della fornitura pi\u00f9 giusta in base alle caratteristiche della stanza da arredare.<\/p>\n<p>I servizi di Boschis Contract sono dunque diversi e versatili: dalla semplice spedizione del mobile richiesto, al progetto totale chiavi in mano, fino all\u2019assistenza post-vendita.<\/p>\n<p>Che si tratti di una ristrutturazione o di una start-up,\u00a0<strong>Boschis Contract<\/strong>\u00a0\u00e8 sempre disponibile a fornire consigli mirati per ogni specifico caso. Sul sito si possono gi\u00e0 trovare alcuni suggerimenti generali e pacchetti gi\u00e0 pronti, ma raccomandiamo sempre di inviare una mail o fare una telefonata per risolvere qualsiasi specifico dubbio.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le origini di Boschis Contract e il nostro impegno nel mondo dell&#8217;interior design!<\/p>\n","protected":false},"author":1,"featured_media":10669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[17],"class_list":["post-3817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita","tag-arredamento-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boschis, Interior Design per piccoli sogni - Boschis Contract Residential<\/title>\n<meta name=\"description\" content=\"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boschis, Interior Design per piccoli sogni - Boschis Contract Residential\" \/>\n<meta property=\"og:description\" content=\"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T14:37:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-15T12:53:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1058\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"Boschis, Interior Design per piccoli sogni\",\"datePublished\":\"2021-12-02T14:37:14+00:00\",\"dateModified\":\"2024-06-15T12:53:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\"},\"wordCount\":321,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg\",\"keywords\":[\"arredamento b&amp;b\"],\"articleSection\":[\"Curiosit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\",\"name\":\"Boschis, Interior Design per piccoli sogni - Boschis Contract Residential\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg\",\"datePublished\":\"2021-12-02T14:37:14+00:00\",\"dateModified\":\"2024-06-15T12:53:52+00:00\",\"description\":\"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg\",\"width\":1600,\"height\":1058},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boschis, Interior Design per piccoli sogni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boschis, Interior Design per piccoli sogni - Boschis Contract Residential","description":"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/","og_locale":"it_IT","og_type":"article","og_title":"Boschis, Interior Design per piccoli sogni - Boschis Contract Residential","og_description":"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!","og_url":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2021-12-02T14:37:14+00:00","article_modified_time":"2024-06-15T12:53:52+00:00","og_image":[{"width":1600,"height":1058,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg","type":"image\/jpeg"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"Boschis, Interior Design per piccoli sogni","datePublished":"2021-12-02T14:37:14+00:00","dateModified":"2024-06-15T12:53:52+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/"},"wordCount":321,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg","keywords":["arredamento b&amp;b"],"articleSection":["Curiosit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/","url":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/","name":"Boschis, Interior Design per piccoli sogni - Boschis Contract Residential","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg","datePublished":"2021-12-02T14:37:14+00:00","dateModified":"2024-06-15T12:53:52+00:00","description":"Boschis Contract si occupa di interior design, proponendo soluzioni su misura: scopri le nostre origini e i nostri servizi!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Boschis-Interior-Design-per-piccoli-sogni.jpg","width":1600,"height":1058},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/boschis-interior-design-per-piccoli-sogni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"Boschis, Interior Design per piccoli sogni"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/3817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=3817"}],"version-history":[{"count":4,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/3817\/revisions"}],"predecessor-version":[{"id":15259,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/3817\/revisions\/15259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/10669"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=3817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=3817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=3817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}