{"id":4122,"date":"2021-12-03T12:51:57","date_gmt":"2021-12-03T11:51:57","guid":{"rendered":"http:\/\/bc2.elwood.agency\/?p=4122"},"modified":"2024-07-22T10:56:05","modified_gmt":"2024-07-22T08:56:05","slug":"arredamento-bb-cosa-aggiungere-nel-periodo-natalizio","status":"publish","type":"post","link":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/","title":{"rendered":"Arredamento del B&#038;B: cosa aggiungere nel periodo natalizio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4122\" class=\"elementor elementor-4122\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e7aed45 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e7aed45\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-786528fa\" data-id=\"786528fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41acb3e elementor-widget elementor-widget-text-editor\" data-id=\"41acb3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.12.1 - 02-04-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<!-- wp:paragraph -->\n<p>Tutte le strutture ricettive subiscono, nel periodo natalizio, alcune trasformazioni: i colori cambiano, si aggiungono piccoli particolari e anche gli spazi esterni sono rallegrati da nuove luci e decorazioni. Nel mese di dicembre (anche se molti partono con gli allestimenti gi\u00e0 a fine ottobre)\u00a0<strong>l&#8217;<a href=\"https:\/\/boschiscontract.it\/residential\/arredo-per-bb-componenti-irrinunciabili\/\">arredamento del b&amp;b<\/a> o di un agriturismo pu\u00f2 essere valorizzato ulteriormente<\/strong>\u00a0con l&#8217;aggiunta di accessori e <a href=\"https:\/\/www.leroymerlin.it\/prodotti\/natale\/decorazioni-natalizie-per-casa\/tutte-decorazioni-natalizie-per-casa\/\">addobbi<\/a> posizionati strategicamente.<br \/>Vediamo cosa non pu\u00f2 proprio mancare!<\/p>\n<!-- \/wp:paragraph --><!-- wp:list -->\n<ul><!-- wp:list-item -->\n<li><strong>Un grande abete con palline e luci<\/strong><br \/>Se possibile, l&#8217;ingresso sarebbe il suo posto ideale, perch\u00e9 permetterebbe di creare subito l&#8217;atmosfera, colpendo chi arriva per la prima volta. In assenza di uno spazio utile, l&#8217;abete addobbato \u00e8 perfetto anche all&#8217;esterno, posizionato in modo da accogliere e letteralmente salutare i nuovi visitatori!<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li><strong>Luci ben visibili all&#8217;esterno della struttura<\/strong><br \/>All&#8217;ingresso, attorno alle porte e alle finestre, a sottolineare alcuni elementi architettonici: le luci di natale sono romantiche e calde, trasmettono al volo un&#8217;idea di famiglia, accoglienza e divertimento. Meglio non esagerare, per\u00f2, per quanto riguarda gli spazi interni: camere e ambienti comuni vanno, s\u00ec, decorati, ma mai resi eccessivamente carichi.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li><strong>Ghirlande sulle porte<\/strong><br \/>Questo vale sia per la porta principale della struttura che per le singole porte delle camere. Un&#8217;altra ottima idea potrebbe essere quella di abbinare anche l&#8217;uso del\u00a0<em>vischio<\/em>. Ghirlande e vischio attirano, infatti, i visitatori, spingono ad aggregarsi e stare insieme, divertono e rappresentano anche un&#8217;ottima occasione per fare delle foto.<\/li>\n<!-- \/wp:list-item --><!-- wp:list-item -->\n<li><strong>Tessuti rossi<\/strong><br \/>Le singole camere non andrebbero eccessivamente modificate, aggiungendo alberi, pacchi o calze appese alle pareti. Quello che si pu\u00f2 fare, per\u00f2, \u00e8 utilizzare tessuti e biancheria per la casa dai colori natalizi, come il rosso o il verde scuro. In questo modo, la camera manterr\u00e0 la sua identit\u00e0, allineandosi con il nuovo spirito natalizio presente nella struttura!<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>Un piccolo consiglio: per Natale, sarebbe l&#8217;ideale poter far affidamento su addobbi\u00a0<em>brandizzati<\/em>. Palline, strisce di tessuto per decorare, biglietti di auguri marchiati col nome della struttura ricettiva sono la soluzione ideale per rendere l&#8217;arredo ancora pi\u00f9 coerente.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Hai dubbi sull&#8217;arredamento del tuo b&amp;b o del tuo agriturismo?<br \/><a href=\"https:\/\/boschiscontract.it\/residential\/contatti\/\">Scrivici o contattaci telefonicamente<\/a>: ti forniremo un&#8217;assistenza su misura!<\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ecco 4 elementi natalizi da non dimenticare per arredare la propria struttura ricettiva: dall&#8217;abete al vischio!<\/p>\n","protected":false},"author":1,"featured_media":10697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[17],"class_list":["post-4122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consigli","tag-arredamento-bb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arredamento del B&amp;B: periodo natalizio - Boschis Contract<\/title>\n<meta name=\"description\" content=\"L&#039;arredamento del B&amp;B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arredamento del B&amp;B: periodo natalizio - Boschis Contract\" \/>\n<meta property=\"og:description\" content=\"L&#039;arredamento del B&amp;B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\" \/>\n<meta property=\"og:site_name\" content=\"Boschis Contract Residential\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-03T11:51:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T08:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elwood_x_boschis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"elwood_x_boschis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\"},\"author\":{\"name\":\"elwood_x_boschis\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\"},\"headline\":\"Arredamento del B&#038;B: cosa aggiungere nel periodo natalizio\",\"datePublished\":\"2021-12-03T11:51:57+00:00\",\"dateModified\":\"2024-07-22T08:56:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg\",\"keywords\":[\"arredamento b&amp;b\"],\"articleSection\":[\"Consigli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\",\"name\":\"Arredamento del B&B: periodo natalizio - Boschis Contract\",\"isPartOf\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg\",\"datePublished\":\"2021-12-03T11:51:57+00:00\",\"dateModified\":\"2024-07-22T08:56:05+00:00\",\"description\":\"L'arredamento del B&B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!\",\"breadcrumb\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg\",\"width\":1600,\"height\":1068},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/boschiscontract.it\/residential\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arredamento del B&#038;B: cosa aggiungere nel periodo natalizio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#website\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"name\":\"Boschis Contract Residential\",\"description\":\"Arredamento strutture ricettive\",\"publisher\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#organization\",\"name\":\"Boschis Contract Residential\",\"url\":\"https:\/\/boschiscontract.it\/residential\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"contentUrl\":\"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg\",\"width\":305.1,\"height\":59.4,\"caption\":\"Boschis Contract Residential\"},\"image\":{\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/search\/top?q=boschiscontract\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298\",\"name\":\"elwood_x_boschis\",\"sameAs\":[\"http:\/\/boschiscontract.it\/residential\"],\"url\":\"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arredamento del B&B: periodo natalizio - Boschis Contract","description":"L'arredamento del B&B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/","og_locale":"it_IT","og_type":"article","og_title":"Arredamento del B&B: periodo natalizio - Boschis Contract","og_description":"L'arredamento del B&B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!","og_url":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/","og_site_name":"Boschis Contract Residential","article_publisher":"https:\/\/www.facebook.com\/search\/top?q=boschiscontract","article_published_time":"2021-12-03T11:51:57+00:00","article_modified_time":"2024-07-22T08:56:05+00:00","og_image":[{"width":1600,"height":1068,"url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg","type":"image\/jpeg"}],"author":"elwood_x_boschis","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"elwood_x_boschis"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#article","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/"},"author":{"name":"elwood_x_boschis","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298"},"headline":"Arredamento del B&#038;B: cosa aggiungere nel periodo natalizio","datePublished":"2021-12-03T11:51:57+00:00","dateModified":"2024-07-22T08:56:05+00:00","mainEntityOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg","keywords":["arredamento b&amp;b"],"articleSection":["Consigli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/","url":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/","name":"Arredamento del B&B: periodo natalizio - Boschis Contract","isPartOf":{"@id":"https:\/\/boschiscontract.it\/residential\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage"},"thumbnailUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg","datePublished":"2021-12-03T11:51:57+00:00","dateModified":"2024-07-22T08:56:05+00:00","description":"L'arredamento del B&B e agriturismi viene valorizzato nel periodo natalizio da tanti addobbi: eccone 4 che proprio non possono mancare!","breadcrumb":{"@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#primaryimage","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2022\/01\/Arredamento-bb-cosa-aggiungere-nel-periodo-natalizio.jpg","width":1600,"height":1068},{"@type":"BreadcrumbList","@id":"https:\/\/boschiscontract.it\/residential\/arredamento-bb-cosa-aggiungere-nel-periodo-natalizio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boschiscontract.it\/residential\/"},{"@type":"ListItem","position":2,"name":"Arredamento del B&#038;B: cosa aggiungere nel periodo natalizio"}]},{"@type":"WebSite","@id":"https:\/\/boschiscontract.it\/residential\/#website","url":"https:\/\/boschiscontract.it\/residential\/","name":"Boschis Contract Residential","description":"Arredamento strutture ricettive","publisher":{"@id":"https:\/\/boschiscontract.it\/residential\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boschiscontract.it\/residential\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/boschiscontract.it\/residential\/#organization","name":"Boschis Contract Residential","url":"https:\/\/boschiscontract.it\/residential\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/","url":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","contentUrl":"https:\/\/boschiscontract.it\/residential\/wp-content\/uploads\/2021\/11\/Logo-Def-residential.svg","width":305.1,"height":59.4,"caption":"Boschis Contract Residential"},"image":{"@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/search\/top?q=boschiscontract"]},{"@type":"Person","@id":"https:\/\/boschiscontract.it\/residential\/#\/schema\/person\/97ab6fae6648aab00a3a6bcd50164298","name":"elwood_x_boschis","sameAs":["http:\/\/boschiscontract.it\/residential"],"url":"https:\/\/boschiscontract.it\/residential\/author\/elwood_x_boschis\/"}]}},"_links":{"self":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/4122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/comments?post=4122"}],"version-history":[{"count":11,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/4122\/revisions"}],"predecessor-version":[{"id":15941,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/posts\/4122\/revisions\/15941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media\/10697"}],"wp:attachment":[{"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/media?parent=4122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/categories?post=4122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boschiscontract.it\/residential\/wp-json\/wp\/v2\/tags?post=4122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}